{"id":25,"count":1,"description":"","link":"https:\/\/www.lesenfantsdefrankie.com\/en\/product-category\/don\/","name":"Don","slug":"don","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.lesenfantsdefrankie.com\/en\/wp-json\/wp\/v2\/product_cat\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesenfantsdefrankie.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.lesenfantsdefrankie.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.lesenfantsdefrankie.com\/en\/wp-json\/wp\/v2\/product?product_cat=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}